{"id":3532,"date":"2019-12-13T09:37:31","date_gmt":"2019-12-13T08:37:31","guid":{"rendered":"https:\/\/www.gigasys.it\/support\/?post_type=manual_kb&#038;p=3532"},"modified":"2019-12-13T14:24:28","modified_gmt":"2019-12-13T13:24:28","slug":"interconnect-trunk-iax","status":"publish","type":"manual_kb","link":"https:\/\/www.gigasys.it\/support\/knowledgebase\/interconnect-trunk-iax\/","title":{"rendered":"Come interconnettere due server VoIP con trunk IAX"},"content":{"rendered":"<p>Dalle appliance Server VoIP \u00e8 possibile creare Linee di tipologia IAX utili per interconnettere pi\u00f9 infrastrutture telefoniche.<\/p>\n<p>Supponendo che gli interni dell&#8217;appliance 1 siano numerati come 20<strong>X<\/strong>, con indirizzo 192.168.1.1 e che gli interni dell&#8217;appliance 2 siano 21<strong>X<\/strong>, con indirizzo 192.168.1.2 la configurazione potrebbe essere come descritto.<\/p>\n<p>Dall&#8217;interfaccia web di gestione di entrambi gli apparati selezionare il men\u00f9 &#8220;Linee&#8221;-&gt; &#8220;Linee&#8221;, selezionare &#8220;Aggiungi Linea&#8221;.<\/p>\n<p>Selezionare come linea da aggiungere &#8220;Linea IAX2 Generica&#8221; e Confermare.<\/p>\n<p>Sull&#8217;<strong>appliance 1<\/strong> inserire come <strong>Nome<\/strong> della linea 200210.<\/p>\n<p>Nei <strong>Dettagli Linea<\/strong> inserire i seguenti parametri di configurazione:<\/p>\n<p>allow=speex<br \/>\ndisallow=all<br \/>\nfromuser=200210<br \/>\nsecret=200210<br \/>\nhost=dynamic<br \/>\ninsecure=very<br \/>\ntype=friend<\/p>\n<p>Utilizzare la <strong>Stringa di Registrazione<\/strong>: 210200:210200@192.168.1.2<\/p>\n<p>Nel Contesto Utente inserire il valore: 210200<\/p>\n<p>Compilare i Dettagli utente con i settaggi seguenti:<\/p>\n<p>allow=speex<br \/>\ndisallow=all<br \/>\nfromuser=210200<br \/>\nsecret=210200<br \/>\nhost=192.168.1.2<br \/>\ninsecure=very<br \/>\ntype=friend<\/p>\n<p>&nbsp;<\/p>\n<p>Sull&#8217;<strong>appliance 2<\/strong> inserire come <strong>Nome<\/strong> della linea 210200.<\/p>\n<p>Nei <strong>Dettagli Linea<\/strong> inserire i seguenti parametri di configurazione:<\/p>\n<p>allow=speex<br \/>\ndisallow=all<br \/>\nfromuser=210200<br \/>\nsecret=210200<br \/>\nhost=dynamic<br \/>\ninsecure=very<br \/>\ntype=friend<\/p>\n<p>Utilizzare la <strong>Stringa di Registrazione<\/strong>: 200210:200210@192.168.1.1<\/p>\n<p>Nel Contesto Utente inserire il valore: 200210<\/p>\n<p>Compilare i Dettagli utente con i settaggi seguenti:<\/p>\n<p>allow=speex<br \/>\ndisallow=all<br \/>\nfromuser=200210<br \/>\nsecret=200210<br \/>\nhost=192.168.1.1<br \/>\ninsecure=very<br \/>\ntype=friend<\/p>\n<p>&nbsp;<\/p>\n<p>Su entrambi i server VoIP configurare <a href=\"https:\/\/www.gigasys.it\/support\/knowledgebase\/chiamate-in-uscita\/\">una regola per le chiamate<\/a> uscenti di utilizzo delle linee appena create nel caso venga composta la numerazione degli interni registrati sulla appliance remota senza l&#8217;utilizzo di prefisso; ad esempio sull&#8217;appliance 1 utilizzare la Linea 200210 se viene composto 21X, sull&#8217;appliance 2 utilizzare la Linea 210200 se viene composto 20X.<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","manualknowledgebasecat":[49],"manual_kb_tag":[220,222,221,86],"class_list":["post-3532","manual_kb","type-manual_kb","status-publish","format-standard","hentry","manualknowledgebasecat-voip","manual_kb_tag-iax","manual_kb_tag-interconnessione","manual_kb_tag-trunk","manual_kb_tag-voip"],"_links":{"self":[{"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manual_kb\/3532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manual_kb"}],"about":[{"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/types\/manual_kb"}],"author":[{"embeddable":true,"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":4,"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manual_kb\/3532\/revisions"}],"predecessor-version":[{"id":3544,"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manual_kb\/3532\/revisions\/3544"}],"wp:attachment":[{"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/media?parent=3532"}],"wp:term":[{"taxonomy":"manualknowledgebasecat","embeddable":true,"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manualknowledgebasecat?post=3532"},{"taxonomy":"manual_kb_tag","embeddable":true,"href":"https:\/\/www.gigasys.it\/support\/wp-json\/wp\/v2\/manual_kb_tag?post=3532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}